{"id":12436,"date":"2026-08-31T14:42:56","date_gmt":"2026-08-31T12:42:56","guid":{"rendered":"https:\/\/www.saltpepper.fr\/?post_type=product&#038;p=12436"},"modified":"2026-08-31T15:51:42","modified_gmt":"2026-08-31T13:51:42","slug":"15-11-10h-atelier-special-eclairs","status":"publish","type":"product","link":"https:\/\/www.saltpepper.fr\/en\/produit\/15-11-10h-atelier-special-eclairs\/","title":{"rendered":"15\/11 \u2013 10h \u2013 Atelier Sp\u00e9cial \u00c9clairs"},"content":{"rendered":"<div class=\"re-c-1rb9ga1\">\n<div class=\"re-c-1rb9ga1\">\n<div class=\"re-c-1rb9ga1\">\n<div class=\"re-c-1rb9ga1\">\n<p data-start=\"69\" data-end=\"410\">Discover all the secrets to making \u00e9clairs worthy of a professional pastry shop! From perfectly mastered choux pastry to creamy fillings and shiny icing, you'll learn to create elegant, delicious, and perfectly uniform \u00e9clairs. A technical, creative, and delicious workshop.<\/p>\n<p data-start=\"69\" data-end=\"410\">\n<\/div>\n<\/div>\n<div class=\"re-c-1rb9ga1\">\n<div class=\"re-c-1rb9ga1\">\n<ul>\n<li data-start=\"454\" data-end=\"531\"><strong data-start=\"454\" data-end=\"483\">Mastering Choux Pastry<\/strong> texture, cooking, and evenness of \u00e9clairs<\/li>\n<li data-start=\"454\" data-end=\"531\"><strong data-start=\"535\" data-end=\"570\">Make different toppings<\/strong> Pastry creams, mousselines, or creative flavors<\/li>\n<li data-start=\"454\" data-end=\"531\"><strong data-start=\"631\" data-end=\"684\">Learn icing and decoration techniques<\/strong> for a professional rendering.<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"re-c-1rb9ga1\">\n<div class=\"re-c-1rb9ga1\">\n<div class=\"re-c-1rb9ga1\"><\/div>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Discover all the secrets to making \u00e9clairs worthy of a professional pastry shop! From perfectly mastered choux pastry to creamy fillings and shiny icing, you'll learn to create elegant, delicious, and perfectly uniform \u00e9clairs. A technical, creative, and delicious workshop.<\/p>","protected":false},"featured_media":2665,"template":"","meta":{"_acf_changed":false},"duree":[30],"nom-de-cours":[48],"thematique":[66],"product_brand":[],"product_cat":[70],"product_tag":[],"class_list":["post-12436","product","type-product","status-publish","has-post-thumbnail","duree-3h","nom-de-cours-atelier-special-eclairs","thematique-patisserie","product_cat-patisserie","first","instock","virtual","taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>15\/11 \u2013 10h \u2013 Atelier Sp\u00e9cial \u00c9clairs - Salt &amp; Pepper<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"15\/11 \u2013 10h \u2013 Atelier Sp\u00e9cial \u00c9clairs - Salt &amp; Pepper\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez tous les secrets pour r\u00e9aliser des \u00e9clairs dignes d\u2019une p\u00e2tisserie professionnelle ! De la p\u00e2te \u00e0 choux parfaitement ma\u00eetris\u00e9e aux cr\u00e8mes onctueuses et au gla\u00e7age brillant, vous apprendrez \u00e0 cr\u00e9er des \u00e9clairs \u00e9l\u00e9gants, gourmands et parfaitement r\u00e9guliers. Un atelier technique, cr\u00e9atif et d\u00e9licieux.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.saltpepper.fr\/en\/product\/15-11-10h-atelier-special-eclairs\/\" \/>\n<meta property=\"og:site_name\" content=\"Salt &amp; Pepper\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/saltandpepper.dijon\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-31T13:51:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.saltpepper.fr\/wp-content\/uploads\/2026\/02\/ChatGPT-Image-13-fevr.-2026-a-12_21_21-1024x683.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.saltpepper.fr\\\/produit\\\/15-11-10h-atelier-special-eclairs\\\/\",\"url\":\"https:\\\/\\\/www.saltpepper.fr\\\/produit\\\/15-11-10h-atelier-special-eclairs\\\/\",\"name\":\"15\\\/11 \u2013 10h \u2013 Atelier Sp\u00e9cial \u00c9clairs - Salt &amp; Pepper\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.saltpepper.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.saltpepper.fr\\\/produit\\\/15-11-10h-atelier-special-eclairs\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.saltpepper.fr\\\/produit\\\/15-11-10h-atelier-special-eclairs\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.saltpepper.fr\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/ChatGPT-Image-13-fevr.-2026-a-12_21_21.png\",\"datePublished\":\"2026-08-31T12:42:56+00:00\",\"dateModified\":\"2026-08-31T13:51:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.saltpepper.fr\\\/produit\\\/15-11-10h-atelier-special-eclairs\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.saltpepper.fr\\\/produit\\\/15-11-10h-atelier-special-eclairs\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.saltpepper.fr\\\/produit\\\/15-11-10h-atelier-special-eclairs\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.saltpepper.fr\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/ChatGPT-Image-13-fevr.-2026-a-12_21_21.png\",\"contentUrl\":\"https:\\\/\\\/www.saltpepper.fr\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/ChatGPT-Image-13-fevr.-2026-a-12_21_21.png\",\"width\":1536,\"height\":1024,\"caption\":\"Cinq \u00e9clairs gourmands et toppings vari\u00e9s avec disques chocolat, fraises, pistaches, fleurs et vin blanc pour atelier culinaire.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.saltpepper.fr\\\/produit\\\/15-11-10h-atelier-special-eclairs\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.saltpepper.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cours de cuisine\",\"item\":\"https:\\\/\\\/www.saltpepper.fr\\\/cours-de-cuisine\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"15\\\/11 \u2013 10h \u2013 Atelier Sp\u00e9cial \u00c9clairs\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.saltpepper.fr\\\/#website\",\"url\":\"https:\\\/\\\/www.saltpepper.fr\\\/\",\"name\":\"Salt & Pepper\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.saltpepper.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.saltpepper.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.saltpepper.fr\\\/#organization\",\"name\":\"Salt & Pepper\",\"url\":\"https:\\\/\\\/www.saltpepper.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.saltpepper.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.saltpepper.fr\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/SALTPEPPER_logotype_cuivre_sans_baseline.svg\",\"contentUrl\":\"https:\\\/\\\/www.saltpepper.fr\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/SALTPEPPER_logotype_cuivre_sans_baseline.svg\",\"width\":1,\"height\":1,\"caption\":\"Salt & Pepper\"},\"image\":{\"@id\":\"https:\\\/\\\/www.saltpepper.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/saltandpepper.dijon\\\/\",\"https:\\\/\\\/www.instagram.com\\\/saltpepper.dijon\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/salt-and-pepper-dijon\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"15\/11 \u2013 10h \u2013 Atelier Sp\u00e9cial \u00c9clairs - Salt &amp; Pepper","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"15\/11 \u2013 10h \u2013 Atelier Sp\u00e9cial \u00c9clairs - Salt &amp; Pepper","og_description":"D\u00e9couvrez tous les secrets pour r\u00e9aliser des \u00e9clairs dignes d\u2019une p\u00e2tisserie professionnelle ! De la p\u00e2te \u00e0 choux parfaitement ma\u00eetris\u00e9e aux cr\u00e8mes onctueuses et au gla\u00e7age brillant, vous apprendrez \u00e0 cr\u00e9er des \u00e9clairs \u00e9l\u00e9gants, gourmands et parfaitement r\u00e9guliers. Un atelier technique, cr\u00e9atif et d\u00e9licieux.","og_url":"https:\/\/www.saltpepper.fr\/en\/product\/15-11-10h-atelier-special-eclairs\/","og_site_name":"Salt &amp; Pepper","article_publisher":"https:\/\/www.facebook.com\/saltandpepper.dijon\/","article_modified_time":"2026-08-31T13:51:42+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/www.saltpepper.fr\/wp-content\/uploads\/2026\/02\/ChatGPT-Image-13-fevr.-2026-a-12_21_21-1024x683.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.saltpepper.fr\/produit\/15-11-10h-atelier-special-eclairs\/","url":"https:\/\/www.saltpepper.fr\/produit\/15-11-10h-atelier-special-eclairs\/","name":"15\/11 \u2013 10h \u2013 Atelier Sp\u00e9cial \u00c9clairs - Salt &amp; Pepper","isPartOf":{"@id":"https:\/\/www.saltpepper.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.saltpepper.fr\/produit\/15-11-10h-atelier-special-eclairs\/#primaryimage"},"image":{"@id":"https:\/\/www.saltpepper.fr\/produit\/15-11-10h-atelier-special-eclairs\/#primaryimage"},"thumbnailUrl":"https:\/\/www.saltpepper.fr\/wp-content\/uploads\/2026\/02\/ChatGPT-Image-13-fevr.-2026-a-12_21_21.png","datePublished":"2026-08-31T12:42:56+00:00","dateModified":"2026-08-31T13:51:42+00:00","breadcrumb":{"@id":"https:\/\/www.saltpepper.fr\/produit\/15-11-10h-atelier-special-eclairs\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.saltpepper.fr\/produit\/15-11-10h-atelier-special-eclairs\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.saltpepper.fr\/produit\/15-11-10h-atelier-special-eclairs\/#primaryimage","url":"https:\/\/www.saltpepper.fr\/wp-content\/uploads\/2026\/02\/ChatGPT-Image-13-fevr.-2026-a-12_21_21.png","contentUrl":"https:\/\/www.saltpepper.fr\/wp-content\/uploads\/2026\/02\/ChatGPT-Image-13-fevr.-2026-a-12_21_21.png","width":1536,"height":1024,"caption":"Cinq \u00e9clairs gourmands et toppings vari\u00e9s avec disques chocolat, fraises, pistaches, fleurs et vin blanc pour atelier culinaire."},{"@type":"BreadcrumbList","@id":"https:\/\/www.saltpepper.fr\/produit\/15-11-10h-atelier-special-eclairs\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.saltpepper.fr\/"},{"@type":"ListItem","position":2,"name":"Cours de cuisine","item":"https:\/\/www.saltpepper.fr\/cours-de-cuisine\/"},{"@type":"ListItem","position":3,"name":"15\/11 \u2013 10h \u2013 Atelier Sp\u00e9cial \u00c9clairs"}]},{"@type":"WebSite","@id":"https:\/\/www.saltpepper.fr\/#website","url":"https:\/\/www.saltpepper.fr\/","name":"Salt &amp; Pepper","description":"","publisher":{"@id":"https:\/\/www.saltpepper.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.saltpepper.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.saltpepper.fr\/#organization","name":"Salt &amp; Pepper","url":"https:\/\/www.saltpepper.fr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.saltpepper.fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.saltpepper.fr\/wp-content\/uploads\/2025\/05\/SALTPEPPER_logotype_cuivre_sans_baseline.svg","contentUrl":"https:\/\/www.saltpepper.fr\/wp-content\/uploads\/2025\/05\/SALTPEPPER_logotype_cuivre_sans_baseline.svg","width":1,"height":1,"caption":"Salt & Pepper"},"image":{"@id":"https:\/\/www.saltpepper.fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/saltandpepper.dijon\/","https:\/\/www.instagram.com\/saltpepper.dijon\/","https:\/\/www.linkedin.com\/company\/salt-and-pepper-dijon\/"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.saltpepper.fr\/en\/wp-json\/wp\/v2\/product\/12436","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.saltpepper.fr\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.saltpepper.fr\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.saltpepper.fr\/en\/wp-json\/wp\/v2\/media\/2665"}],"wp:attachment":[{"href":"https:\/\/www.saltpepper.fr\/en\/wp-json\/wp\/v2\/media?parent=12436"}],"wp:term":[{"taxonomy":"duree","embeddable":true,"href":"https:\/\/www.saltpepper.fr\/en\/wp-json\/wp\/v2\/duree?post=12436"},{"taxonomy":"nom-de-cours","embeddable":true,"href":"https:\/\/www.saltpepper.fr\/en\/wp-json\/wp\/v2\/nom-de-cours?post=12436"},{"taxonomy":"thematique","embeddable":true,"href":"https:\/\/www.saltpepper.fr\/en\/wp-json\/wp\/v2\/thematique?post=12436"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.saltpepper.fr\/en\/wp-json\/wp\/v2\/product_brand?post=12436"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.saltpepper.fr\/en\/wp-json\/wp\/v2\/product_cat?post=12436"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.saltpepper.fr\/en\/wp-json\/wp\/v2\/product_tag?post=12436"}],"curies":[{"name":"WP","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}